{"id":2524,"date":"2021-03-11T14:36:00","date_gmt":"2021-03-11T19:36:00","guid":{"rendered":"https:\/\/adisoke.ca\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/"},"modified":"2023-10-11T12:59:56","modified_gmt":"2023-10-11T16:59:56","slug":"mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle","status":"publish","type":"news-post","link":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/","title":{"rendered":"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle"},"content":{"rendered":"<p>Un avis a \u00e9t\u00e9 envoy\u00e9 aux personnes qui vivent \u00e0 proximit\u00e9 du chantier de construction de l&rsquo;installation partag\u00e9e de la Biblioth\u00e8que publique d&rsquo;Ottawa et de Biblioth\u00e8que et Archives Canada. Il a pour but de les informer que les travaux de construction sur le site s&rsquo;intensifient et de les informer des activit\u00e9s de construction pr\u00e9vues d&rsquo;ici la fin mai 2021.<br \/>\n<strong>Quoi\u00a0:<\/strong>\u00a0\u00a0\u00a0 La Biblioth\u00e8que publique d\u2019Ottawa (BPO) et Biblioth\u00e8que et Archives Canada (BAC) s\u2019associent pour am\u00e9nager une installation partag\u00e9e qui abritera la nouvelle Biblioth\u00e8que centrale de la BPO ainsi que les locaux des programmes et des services publics de BAC dans la r\u00e9gion de la capitale nationale.<\/p>\n<p><strong>Quand\u00a0: <\/strong>Les travaux reprendront sur le chantier (sout\u00e8nement, forage, excavation g\u00e9n\u00e9rale, etc.) et devraient se poursuivre jusqu\u2019\u00e0 la fin du mois de mai 2021.<\/p>\n<p><strong>O\u00f9\u00a0:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong>Les travaux se d\u00e9rouleront sur le site des nouvelles installations, au 555, rue Albert, entre les rues Commissioner et Empress.<\/p>\n<p><strong>Qui\u00a0:<\/strong>\u00a0\u00a0\u00a0\u00a0\u00a0 Au nom des partenaires du projet, la Ville d\u2019Ottawa a retenu les services de l\u2019entrepreneur PCL pour ex\u00e9cuter les premiers travaux pr\u00e9paratoires. La Ville lancera l\u2019appel d\u2019offres pour s\u00e9lectionner un entrepreneur g\u00e9n\u00e9ral pour le projet au printemps\u00a02021, et la construction de l\u2019installation devrait commencer \u00e0 l\u2019automne 2021.<\/p>\n<p><strong>Inconv\u00e9nients caus\u00e9s par les travaux<\/strong><\/p>\n<p>L\u2019entrepreneur prendra toutes les pr\u00e9cautions n\u00e9cessaires pour minimiser les r\u00e9percussions des travaux sur la vie quotidienne de votre famille ou l\u2019exploitation normale de votre entreprise. Comme c\u2019est souvent le cas avec ce type de travaux, vous devez vous attendre \u00e0 certains inconv\u00e9nients, comme un ralentissement de la circulation, des restrictions concernant le stationnement, du bruit, de l\u2019\u00e9clairage et de la poussi\u00e8re. Il est \u00e9galement possible que vous ressentiez des vibrations en raison de l\u2019utilisation d\u2019\u00e9quipement lourd. Il s\u2019agit d\u2019une situation courante qui ne cause g\u00e9n\u00e9ralement pas de probl\u00e8me.<\/p>\n<p>Comme le chantier se trouve \u00e0 proximit\u00e9 d\u2019infrastructures essentielles, des capteurs de vibrations et de surveillance ont \u00e9t\u00e9 install\u00e9s sur chacun des \u00e9l\u00e9ments d\u2019infrastructures essentielles en question. Ces capteurs alerteront l\u2019\u00e9quipe du projet de tout d\u00e9passement des limites prescrites pour les vibrations ou les mouvements. Aucun d\u00e9passement n\u2019a \u00e9t\u00e9 enregistr\u00e9 \u00e0 ce jour. Voici ce \u00e0 quoi doivent s\u2019attendre ceux qui r\u00e9sident \u00e0 proximit\u00e9 du chantier au cours des prochains mois\u00a0:<\/p>\n<ul>\n<li>Les travaux reprendront sur le chantier (sout\u00e8nement, forage, excavation g\u00e9n\u00e9rale, etc.) et devraient se poursuivre jusqu\u2019\u00e0 la fin du mois de mai 2021.<\/li>\n<li>De 7\u00a0h \u00e0 17\u00a0h du lundi au vendredi (et conform\u00e9ment aux horaires de chantier, \u00e9tablis par le gouvernement provincial et le R\u00e8glement sur le bruit de la Ville), les travaux vont engendrer de forts bruits li\u00e9s aux activit\u00e9s de forage et \u00e0 l\u2019utilisation d\u2019\u00e9quipement de construction\/camions.<\/li>\n<li>Les travaux vont commencer \u00e0 proximit\u00e9 de la rue Commissioner et se poursuivront vers l\u2019ouest le long de la rue Albert.<\/li>\n<\/ul>\n<p>Nous nous engageons envers les r\u00e9sidents vivant dans le secteur de construction \u00e0 continuer \u00e0 leur fournir des informations opportunes sur ce \u00e0 quoi ils doivent s&rsquo;attendre en vivant et en travaillant \u00e0 proximit\u00e9 du chantier.<\/p>\n<p><strong>Journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle<\/strong><\/p>\n<p>Comme la COVID-19 emp\u00eache tout rassemblement en personne pour le moment, une journ\u00e9e portes ouvertes virtuelle aura lieu le mardi 30 mars \u00e0 18 h (d&rsquo;une dur\u00e9e d&rsquo;une heure environ). L\u2019\u00e9quipe de projet se pr\u00e9sentera et offrira un aper\u00e7u du calendrier de l\u2019ensemble des travaux et une description du type d\u2019activit\u00e9s pr\u00e9vues dans le cadre des travaux pr\u00e9paratoires. \u00c0 l\u2019issue de la pr\u00e9sentation, les r\u00e9sidents pourront \u00e9galement poser des questions. La s\u00e9ance se d\u00e9roulera en anglais, mais la traduction simultan\u00e9e sera offerte. Pour les d\u00e9tails Zoom de cette activit\u00e9 :<\/p>\n<p><a href=\"https:\/\/zoom.us\/j\/92869778236?pwd=ZGZIaFo4MG5jQnpYYXMvb1A3c0tHQT09\">https:\/\/zoom.us\/j\/92869778236?pwd=ZGZIaFo4MG5jQnpYYXMvb1A3c0tHQT09<\/a><\/p>\n<p>ID : 928 6977 8236. Mot de passe: 828262<\/p>\n<p><strong>Coordonn\u00e9es<\/strong><\/p>\n<p>Pour toute urgence en dehors des heures de travail normales, veuillez communiquer avec la Ville en composant le 3-1-1. Pour obtenir des renseignements g\u00e9n\u00e9raux sur le projet, veuillez envoyer un courriel \u00e0 centrallibrary@ottawa.ca ou communiquer avec le gestionnaire de projet de la Ville.<\/p>\n<p><strong>\u00a0<\/strong><strong>Gestionnaire de projet de la Ville\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 <\/strong><\/p>\n<p>Simon Dupuis, Construction et design, <a href=\"mailto:simon.dupuis@ottawa.ca\">simon.dupuis@ottawa.ca<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un avis a \u00e9t\u00e9 envoy\u00e9 aux personnes qui vivent \u00e0 proximit\u00e9 du chantier de construction de l&rsquo;installation partag\u00e9e de la Biblioth\u00e8que publique d&rsquo;Ottawa et de Biblioth\u00e8que et Archives Canada. Il a pour but de les informer que les travaux de construction sur le site s&rsquo;intensifient et de les informer des activit\u00e9s de construction pr\u00e9vues d&rsquo;ici&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2540,"template":"","news-category":[39,26,41],"news-year":[55],"class_list":["post-2524","news-post","type-news-post","status-publish","has-post-thumbnail","hentry","news-category-construction-fr","news-category-message-dinteret-public","news-category-participation","news-year-2021-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle\" \/>\n<meta property=\"og:description\" content=\"Un avis a \u00e9t\u00e9 envoy\u00e9 aux personnes qui vivent \u00e0 proximit\u00e9 du chantier de construction de l&rsquo;installation partag\u00e9e de la Biblioth\u00e8que publique d&rsquo;Ottawa et de Biblioth\u00e8que et Archives Canada. Il a pour but de les informer que les travaux de construction sur le site s&rsquo;intensifient et de les informer des activit\u00e9s de construction pr\u00e9vues d&rsquo;ici...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0101dis\u014dke\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T16:59:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/\",\"name\":\"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-C_Albert-Full.jpg\",\"datePublished\":\"2021-03-11T19:36:00+00:00\",\"dateModified\":\"2023-10-11T16:59:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-C_Albert-Full.jpg\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-C_Albert-Full.jpg\",\"width\":1600,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"name\":\"\u0101dis\u014dke\",\"description\":\"Stories live here.\",\"publisher\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adisoke.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\",\"name\":\"\u0101dis\u014dke\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"width\":850,\"height\":202,\"caption\":\"\u0101dis\u014dke\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/","og_locale":"fr_FR","og_type":"article","og_title":"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle","og_description":"Un avis a \u00e9t\u00e9 envoy\u00e9 aux personnes qui vivent \u00e0 proximit\u00e9 du chantier de construction de l&rsquo;installation partag\u00e9e de la Biblioth\u00e8que publique d&rsquo;Ottawa et de Biblioth\u00e8que et Archives Canada. Il a pour but de les informer que les travaux de construction sur le site s&rsquo;intensifient et de les informer des activit\u00e9s de construction pr\u00e9vues d&rsquo;ici...","og_url":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/","og_site_name":"\u0101dis\u014dke","article_modified_time":"2023-10-11T16:59:56+00:00","og_image":[{"width":850,"height":202,"url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/","url":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/","name":"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle","isPartOf":{"@id":"https:\/\/adisoke.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/#primaryimage"},"image":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/#primaryimage"},"thumbnailUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-C_Albert-Full.jpg","datePublished":"2021-03-11T19:36:00+00:00","dateModified":"2023-10-11T16:59:56+00:00","breadcrumb":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/#primaryimage","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-C_Albert-Full.jpg","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-C_Albert-Full.jpg","width":1600,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/adisoke.ca\/fr\/news-post\/mises-a-jour-avis-de-construction-et-journee-portes-ouvertes-virtuelle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adisoke.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Mises \u00e0 jour : avis de construction et journ\u00e9e \u00ab portes ouvertes \u00bb virtuelle"}]},{"@type":"WebSite","@id":"https:\/\/adisoke.ca\/#website","url":"https:\/\/adisoke.ca\/","name":"\u0101dis\u014dke","description":"Stories live here.","publisher":{"@id":"https:\/\/adisoke.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adisoke.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/adisoke.ca\/#organization","name":"\u0101dis\u014dke","url":"https:\/\/adisoke.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","width":850,"height":202,"caption":"\u0101dis\u014dke"},"image":{"@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post"}],"about":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/types\/news-post"}],"author":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2524\/revisions"}],"predecessor-version":[{"id":5248,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2524\/revisions\/5248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media\/2540"}],"wp:attachment":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media?parent=2524"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-category?post=2524"},{"taxonomy":"news-year","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-year?post=2524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}