{"id":2532,"date":"2021-08-03T09:27:00","date_gmt":"2021-08-03T13:27:00","guid":{"rendered":"https:\/\/adisoke.ca\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/"},"modified":"2023-10-11T12:59:40","modified_gmt":"2023-10-11T16:59:40","slug":"devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac","status":"publish","type":"news-post","link":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/","title":{"rendered":"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC"},"content":{"rendered":"<p>Jeudi 5 ao\u00fbt 202111 h 15 <\/p>\n<p>L\u2019histoire de la nouvelle installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada est l\u2019histoire d\u2019une collaboration pour cr\u00e9er des liens. Reconnaissant que le nouveau b\u00e2timent est situ\u00e9 sur le territoire traditionnel non c\u00e9d\u00e9 de la nation algonquine Anishin\u0101be, qui vit dans la r\u00e9gion depuis des temps imm\u00e9moriaux, il \u00e9tait essentiel de s\u2019associer avec la nation h\u00f4te tout au long du processus de planification et de conception.<\/p>\n<p>Afin d\u2019am\u00e9liorer les relations avec la nation h\u00f4te et pour respecter la vision d\u2019un b\u00e2timent con\u00e7u pour \u00eatre inclusif et accueillant pour tous, l\u2019installation se verra donner un nom en Anishin\u0101bemowin par la nation h\u00f4te.<\/p>\n<p><a href=\"https:\/\/can01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fottawacentrallibrary.us11.list-manage.com%2Ftrack%2Fclick%3Fu%3D699260e5bdf4451e3c8f4b788%26id%3D7add89af90%26e%3Da35b55749d&#038;data=04%7C01%7Cbyrne.furlong%40ottawa.ca%7C52475725c8df4d9f437208d95677935c%7Cdfcc033ddf874c6ea1b88eaa73f1b72e%7C0%7C0%7C637635893845926639%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&#038;sdata=H3okf19LpIGf55SmtHa%2BiSZ9Imn0V6cA5BQYILc98Xc%3D&#038;reserved=0\" rel=\"noopener\" target=\"_blank\">Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation.<\/a> Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.<\/p>\n<p>Nous esp\u00e9rons que vous pourrez vous joindre \u00e0 nous par voie virtuelle afin de c\u00e9l\u00e9brer l\u2019approche unique et distinctive de l\u2019appellation de l\u2019installation partag\u00e9e et de faire conna\u00eetre le sens et l\u2019importance du nom. Cet \u00e9v\u00e9nement repr\u00e9sente un \u00e9l\u00e9ment important de la cr\u00e9ation d\u2019une institution publique inclusive et remarquable et un pas significatif vers la r\u00e9conciliation. <\/p>\n<p>Pour visionner l\u2019\u00e9v\u00e9nement en direct, veuillez <a href=\"https:\/\/can01.safelinks.protection.outlook.com\/?url=https%3A%2F%2Fottawacentrallibrary.us11.list-manage.com%2Ftrack%2Fclick%3Fu%3D699260e5bdf4451e3c8f4b788%26id%3D7add89af90%26e%3Da35b55749d&#038;data=04%7C01%7Cbyrne.furlong%40ottawa.ca%7C52475725c8df4d9f437208d95677935c%7Cdfcc033ddf874c6ea1b88eaa73f1b72e%7C0%7C0%7C637635893845926639%7CUnknown%7CTWFpbGZsb3d8eyJWIjoiMC4wLjAwMDAiLCJQIjoiV2luMzIiLCJBTiI6Ik1haWwiLCJXVCI6Mn0%3D%7C1000&#038;sdata=H3okf19LpIGf55SmtHa%2BiSZ9Imn0V6cA5BQYILc98Xc%3D&#038;reserved=0\" rel=\"noopener\" target=\"_blank\">visiter la cha\u00eene YouTube de la Ville d\u2019Ottawa.<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jeudi 5 ao\u00fbt 202111 h 15 L\u2019histoire de la nouvelle installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada est l\u2019histoire d\u2019une collaboration pour cr\u00e9er des liens. Reconnaissant que le nouveau b\u00e2timent est situ\u00e9 sur le territoire traditionnel non c\u00e9d\u00e9 de la nation algonquine Anishin\u0101be, qui vit dans la r\u00e9gion depuis&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2544,"template":"","news-category":[43],"news-year":[55],"class_list":["post-2532","news-post","type-news-post","status-publish","has-post-thumbnail","hentry","news-category-grandes-etapes","news-year-2021-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC<\/title>\n<meta name=\"description\" content=\"Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation. Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC\" \/>\n<meta property=\"og:description\" content=\"Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation. Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0101dis\u014dke\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T16:59:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/\",\"name\":\"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/news-update-bg.jpg\",\"datePublished\":\"2021-08-03T13:27:00+00:00\",\"dateModified\":\"2023-10-11T16:59:40+00:00\",\"description\":\"Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation. Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/news-update-bg.jpg\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/news-update-bg.jpg\",\"width\":1350,\"height\":901},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"name\":\"\u0101dis\u014dke\",\"description\":\"Stories live here.\",\"publisher\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adisoke.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\",\"name\":\"\u0101dis\u014dke\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"width\":850,\"height\":202,\"caption\":\"\u0101dis\u014dke\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC","description":"Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation. Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/","og_locale":"fr_FR","og_type":"article","og_title":"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC","og_description":"Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation. Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.","og_url":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/","og_site_name":"\u0101dis\u014dke","article_modified_time":"2023-10-11T16:59:40+00:00","og_image":[{"width":850,"height":202,"url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/","url":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/","name":"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC","isPartOf":{"@id":"https:\/\/adisoke.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/#primaryimage"},"image":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/#primaryimage"},"thumbnailUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/news-update-bg.jpg","datePublished":"2021-08-03T13:27:00+00:00","dateModified":"2023-10-11T16:59:40+00:00","description":"Vous \u00eates invit\u00e9 \u00e0 participer \u00e0 l\u2019\u00e9v\u00e9nement pour le d\u00e9voilement du nom de l\u2019installation. Au cours de l\u2019\u00e9v\u00e9nement en direct, des A\u00een\u00e9s et des membres de la nation h\u00f4te partageront l\u2019histoire du nom et les raisons pour lesquelles il r\u00e9sonne pour l\u2019installation.","breadcrumb":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/#primaryimage","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/news-update-bg.jpg","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/news-update-bg.jpg","width":1350,"height":901},{"@type":"BreadcrumbList","@id":"https:\/\/adisoke.ca\/fr\/news-post\/devoilement-du-nouveau-nom-de-votre-nouvelle-installation-partagee-bpo-bac\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adisoke.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"D\u00e9voilement du nouveau nom de votre nouvelle installation partag\u00e9e BPO-BAC"}]},{"@type":"WebSite","@id":"https:\/\/adisoke.ca\/#website","url":"https:\/\/adisoke.ca\/","name":"\u0101dis\u014dke","description":"Stories live here.","publisher":{"@id":"https:\/\/adisoke.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adisoke.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/adisoke.ca\/#organization","name":"\u0101dis\u014dke","url":"https:\/\/adisoke.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","width":850,"height":202,"caption":"\u0101dis\u014dke"},"image":{"@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post"}],"about":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/types\/news-post"}],"author":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2532\/revisions"}],"predecessor-version":[{"id":5246,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2532\/revisions\/5246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media\/2544"}],"wp:attachment":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media?parent=2532"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-category?post=2532"},{"taxonomy":"news-year","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-year?post=2532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}