{"id":2556,"date":"2020-06-15T13:01:00","date_gmt":"2020-06-15T17:01:00","guid":{"rendered":"https:\/\/adisoke.ca\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/"},"modified":"2023-10-11T13:02:58","modified_gmt":"2023-10-11T17:02:58","slug":"demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee","status":"publish","type":"news-post","link":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/","title":{"rendered":"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e"},"content":{"rendered":"<p><strong>Le 15\u00a0juin\u00a02020<\/strong> \u2013 Les Services de l\u2019approvisionnement de la Ville d\u2019Ottawa ont publi\u00e9 une <a href=\"https:\/\/www.merx.com\/cityofottawa\/solicitations\/open-bids\/PIED-IS-CLPB-OPL-LAC-Joint-Facility\/0000177915?language=FR\">demande de qualification<\/a> (DDQ) en vue de pr\u00e9s\u00e9lectionner des entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada. Pour assurer l\u2019\u00e9quit\u00e9, l\u2019ouverture, la transparence et le respect de cette DDQ et de son processus, la Ville d\u2019Ottawa a fait appel aux services d\u2019un commissaire \u00e0 l\u2019\u00e9quit\u00e9.<br \/>\nLa DDG a pour but de cr\u00e9er une liste des candidats qui ont les qualifications et l\u2019exp\u00e9rience n\u00e9cessaires pour g\u00e9rer et superviser la construction de l\u2019installation partag\u00e9e. Pour \u00eatre retenus, les entrepreneurs devront avoir fait leurs preuves et d\u00e9montrer qu\u2019ils ont la capacit\u00e9 de fournir les services demand\u00e9s\u00a0:<\/p>\n<ul>\n<li>R\u00e9alisation de projets d\u2019envergure, de port\u00e9e et de complexit\u00e9 comparables;<\/li>\n<li>Exp\u00e9rience av\u00e9r\u00e9e en production de rapports et en gestion d\u2019\u00e9ch\u00e9anciers;<\/li>\n<li>Exp\u00e9rience av\u00e9r\u00e9e en planification des travaux et des \u00e9tapes, en ex\u00e9cution de projets et en gestion du changement;<\/li>\n<li>Exp\u00e9rience av\u00e9r\u00e9e dans la mise en service, l\u2019am\u00e9nagement et la cession d\u2019installations, et dans la gestion de projets visant la certification LEED.<\/li>\n<\/ul>\n<p>L\u2019\u00e9tape de pr\u00e9s\u00e9lection a toujours fait partie int\u00e9grante de l\u2019\u00e9ch\u00e9ancier du projet et est particuli\u00e8rement importante dans le contexte actuel. La cr\u00e9ation d\u2019une liste d\u2019entrepreneurs g\u00e9n\u00e9raux pr\u00e9qualifi\u00e9s permettra \u00e0 l\u2019\u00e9quipe de projet de traiter rapidement des effets potentiels de la COVID-19, ainsi que du budget et de l\u2019\u00e9ch\u00e9ancier.<\/p>\n<p>Le processus de pr\u00e9s\u00e9lection se terminera \u00e0 la fin du mois de juillet\u00a02020. Pour en savoir plus sur l\u2019installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada, consultez le site <a href=\"https:\/\/adisoke.ca\/fr\/\">inspirez555.ca<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le 15\u00a0juin\u00a02020 \u2013 Les Services de l\u2019approvisionnement de la Ville d\u2019Ottawa ont publi\u00e9 une demande de qualification (DDQ) en vue de pr\u00e9s\u00e9lectionner des entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada. Pour assurer l\u2019\u00e9quit\u00e9, l\u2019ouverture, la transparence et le respect de cette DDQ et&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2565,"template":"","news-category":[41],"news-year":[54],"class_list":["post-2556","news-post","type-news-post","status-publish","has-post-thumbnail","hentry","news-category-participation","news-year-2020-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Le 15\u00a0juin\u00a02020 \u2013 Les Services de l\u2019approvisionnement de la Ville d\u2019Ottawa ont publi\u00e9 une demande de qualification (DDQ) en vue de pr\u00e9s\u00e9lectionner des entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada. Pour assurer l\u2019\u00e9quit\u00e9, l\u2019ouverture, la transparence et le respect de cette DDQ et...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0101dis\u014dke\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T17:02:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/\",\"name\":\"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-D_Pimici-Night.jpg\",\"datePublished\":\"2020-06-15T17:01:00+00:00\",\"dateModified\":\"2023-10-11T17:02:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-D_Pimici-Night.jpg\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-D_Pimici-Night.jpg\",\"width\":1600,\"height\":900,\"caption\":\"View at night of Pimici Entrance\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"name\":\"\u0101dis\u014dke\",\"description\":\"Stories live here.\",\"publisher\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adisoke.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\",\"name\":\"\u0101dis\u014dke\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"width\":850,\"height\":202,\"caption\":\"\u0101dis\u014dke\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/","og_locale":"fr_FR","og_type":"article","og_title":"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e","og_description":"Le 15\u00a0juin\u00a02020 \u2013 Les Services de l\u2019approvisionnement de la Ville d\u2019Ottawa ont publi\u00e9 une demande de qualification (DDQ) en vue de pr\u00e9s\u00e9lectionner des entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada. Pour assurer l\u2019\u00e9quit\u00e9, l\u2019ouverture, la transparence et le respect de cette DDQ et...","og_url":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/","og_site_name":"\u0101dis\u014dke","article_modified_time":"2023-10-11T17:02:58+00:00","og_image":[{"width":850,"height":202,"url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/","url":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/","name":"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e","isPartOf":{"@id":"https:\/\/adisoke.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/#primaryimage"},"image":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/#primaryimage"},"thumbnailUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-D_Pimici-Night.jpg","datePublished":"2020-06-15T17:01:00+00:00","dateModified":"2023-10-11T17:02:58+00:00","breadcrumb":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/#primaryimage","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-D_Pimici-Night.jpg","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-D_Pimici-Night.jpg","width":1600,"height":900,"caption":"View at night of Pimici Entrance"},{"@type":"BreadcrumbList","@id":"https:\/\/adisoke.ca\/fr\/news-post\/demande-de-qualification-visant-la-preselection-dentrepreneurs-generaux-pour-la-construction-de-linstallation-partagee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adisoke.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Demande de qualification visant la pr\u00e9s\u00e9lection d\u2019entrepreneurs g\u00e9n\u00e9raux pour la construction de l\u2019installation partag\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/adisoke.ca\/#website","url":"https:\/\/adisoke.ca\/","name":"\u0101dis\u014dke","description":"Stories live here.","publisher":{"@id":"https:\/\/adisoke.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adisoke.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/adisoke.ca\/#organization","name":"\u0101dis\u014dke","url":"https:\/\/adisoke.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","width":850,"height":202,"caption":"\u0101dis\u014dke"},"image":{"@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post"}],"about":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/types\/news-post"}],"author":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2556\/revisions"}],"predecessor-version":[{"id":5269,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2556\/revisions\/5269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media\/2565"}],"wp:attachment":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media?parent=2556"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-category?post=2556"},{"taxonomy":"news-year","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-year?post=2556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}