{"id":2572,"date":"2020-10-22T15:48:00","date_gmt":"2020-10-22T19:48:00","guid":{"rendered":"https:\/\/adisoke.ca\/news-post\/sondage-en-ligne-aupres-des-autochtones\/"},"modified":"2023-10-11T13:02:03","modified_gmt":"2023-10-11T17:02:03","slug":"sondage-en-ligne-aupres-des-autochtones","status":"publish","type":"news-post","link":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/","title":{"rendered":"Sondage en ligne aupr\u00e8s des Autochtones"},"content":{"rendered":"<p>L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.<br \/>\nAu nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue <a href=\"https:\/\/fr.surveymonkey.com\/r\/ML5XCW7\">un sondage en ligne sur la consultation des Autochtones<\/a>.<\/p>\n<p>Les questions de ce sondage portent notamment sur la conception des espaces int\u00e9rieurs et ext\u00e9rieurs, de m\u00eame que sur les types d\u2019activit\u00e9s, les programmes, les collections et les services, par exemple\u00a0:<\/p>\n<ul>\n<li>Qu\u2019est\u2011ce qui pourrait vous convaincre de visiter la nouvelle installation?<\/li>\n<li>Bien que nous respections le fait que cette installation partag\u00e9e soit am\u00e9nag\u00e9e sur le territoire de la nation algonquine et que des \u00e9l\u00e9ments de la culture algonquine soient int\u00e9gr\u00e9s dans la conception, comment pouvons-nous int\u00e9grer d\u2019autres \u00e9l\u00e9ments de la culture des Premi\u00e8res Nations, des Inuits et des M\u00e9tis dans la conception de l\u2019installation partag\u00e9e pour qu\u2019elle soit accueillante, respectueuse et inclusive?<\/li>\n<li>Un auditorium sera am\u00e9nag\u00e9 dans l\u2019installation. Ce vaste espace polyvalent sera un point de mire de l\u2019activit\u00e9 communautaire, sociale, \u00e9ducative et culturelle. Il comprendra des espaces o\u00f9 se d\u00e9rouleront des spectacles, des programmes, des \u00e9v\u00e9nements et des assembl\u00e9es. Quelles activit\u00e9s souhaiteriez-vous que l\u2019on organise dans cet espace?<\/li>\n<li>Des \u0153uvres d\u2019art public, notamment une s\u00e9rie d\u2019\u0153uvres d\u2019artistes autochtones seront expos\u00e9es dans toute l\u2019installation partag\u00e9e. Qu\u2019est-ce que vous souhaiteriez que ces \u0153uvres permettent de r\u00e9aliser ou d\u2019accomplir \u00e0 l\u2019int\u00e9rieur comme \u00e0 l\u2019ext\u00e9rieur de ce b\u00e2timent?<\/li>\n<li>L\u2019installation est dot\u00e9e d\u2019un vaste espace de cr\u00e9ation pour l\u2019apprentissage pratique dans le cadre des programmes num\u00e9riques et d\u2019artisanat traditionnels. Quels sont les types de programmes ou d\u2019outils qui devraient, \u00e0 votre avis, \u00eatre offerts dans cet espace de cr\u00e9ation?<\/li>\n<\/ul>\n<p>Le sondage en ligne sur la consultation des Autochtones fournira \u00e0 l\u2019\u00e9quipe de projet des informations cl\u00e9s sur la fa\u00e7on dont elle pourra rendre l\u2019installation plus repr\u00e9sentative et inclusive de tous les visiteurs des Premi\u00e8res Nations, des Inuits et des M\u00e9tis.<\/p>\n<p>Ce sondage sera en ligne jusqu\u2019au 30 novembre\u00a02020.<\/p>\n<p>Les personnes d\u00e9sireuses de participer par un autre moyen peuvent \u00e9galement y r\u00e9pondre par t\u00e9l\u00e9phone ou demander qu\u2019un exemplaire leur soit post\u00e9 en communiquant avec <a href=\"mailto:CentralLibrary@ottawa.ca\">CentralLibrary@ottawa.ca<\/a>. Pour <a href=\"https:\/\/adisoke.ca\/fr\/bibliotheque-archives-courriel\/\">consulter les coordonn\u00e9es des personnes-ressources<\/a>, <a href=\"https:\/\/adisoke.ca\/fr\/participation-autochtone\/\">les activit\u00e9s pr\u00e9c\u00e9dentes de consultation des Autochtones<\/a> ou pour obtenir de plus amples renseignements au sujet de l\u2019installation partag\u00e9e de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada, veuillez visiter le site Web du projet <a href=\"https:\/\/adisoke.ca\/fr\/\">Inspirez555.ca<\/a>.<\/p>\n<p><strong>Renseignements g\u00e9n\u00e9raux<\/strong><\/p>\n<p>La BPO et BAC travaillent en partenariat dans l\u2019am\u00e9nagement de la nouvelle installation partag\u00e9e qui abritera la nouvelle biblioth\u00e8que centrale de la BPO ainsi que les programmes et les services publics de BAC. Dans le cadre de ce projet d\u00e9fricheur, deux grandes institutions publiques se sont alli\u00e9es pour construire un lieu qui, lorsqu\u2019il ouvrira ses portes \u00e0 la fin de 2024, accueillera les r\u00e9sidents d\u2019Ottawa, les Canadiens et Canadiennes et les visiteurs venus de partout dans le monde pour apprendre, d\u00e9couvrir et cr\u00e9er.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e. Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2578,"template":"","news-category":[41,42],"news-year":[54],"class_list":["post-2572","news-post","type-news-post","status-publish","has-post-thumbnail","hentry","news-category-participation","news-category-peuples-autochtones","news-year-2020-fr"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sondage en ligne aupr\u00e8s des Autochtones<\/title>\n<meta name=\"description\" content=\"L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue un sondage en ligne sur la consultation des Autochtones.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sondage en ligne aupr\u00e8s des Autochtones\" \/>\n<meta property=\"og:description\" content=\"L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue un sondage en ligne sur la consultation des Autochtones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0101dis\u014dke\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T17:02:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"202\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/\",\"name\":\"Sondage en ligne aupr\u00e8s des Autochtones\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-C_Albert-East-scaled.jpg\",\"datePublished\":\"2020-10-22T19:48:00+00:00\",\"dateModified\":\"2023-10-11T17:02:03+00:00\",\"description\":\"L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue un sondage en ligne sur la consultation des Autochtones.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/#primaryimage\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-C_Albert-East-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/VCAM-C_Albert-East-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/news-post\\\/sondage-en-ligne-aupres-des-autochtones\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/adisoke.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sondage en ligne aupr\u00e8s des Autochtones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#website\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"name\":\"\u0101dis\u014dke\",\"description\":\"Stories live here.\",\"publisher\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/adisoke.ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#organization\",\"name\":\"\u0101dis\u014dke\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"contentUrl\":\"https:\\\/\\\/adisoke.ca\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png\",\"width\":850,\"height\":202,\"caption\":\"\u0101dis\u014dke\"},\"image\":{\"@id\":\"https:\\\/\\\/adisoke.ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sondage en ligne aupr\u00e8s des Autochtones","description":"L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue un sondage en ligne sur la consultation des Autochtones.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/","og_locale":"fr_FR","og_type":"article","og_title":"Sondage en ligne aupr\u00e8s des Autochtones","og_description":"L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue un sondage en ligne sur la consultation des Autochtones.","og_url":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/","og_site_name":"\u0101dis\u014dke","article_modified_time":"2023-10-11T17:02:03+00:00","og_image":[{"width":850,"height":202,"url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/","url":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/","name":"Sondage en ligne aupr\u00e8s des Autochtones","isPartOf":{"@id":"https:\/\/adisoke.ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/#primaryimage"},"image":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/#primaryimage"},"thumbnailUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-C_Albert-East-scaled.jpg","datePublished":"2020-10-22T19:48:00+00:00","dateModified":"2023-10-11T17:02:03+00:00","description":"L\u2019\u00e9quipe de projet de l\u2019installation conjointe de la Biblioth\u00e8que publique d\u2019Ottawa et de Biblioth\u00e8que et Archives Canada offre, aux peuples autochtones de la r\u00e9gion d\u2019Ottawa-Gatineau et de tout le Canada, l\u2019occasion d\u2019exprimer des id\u00e9es, des suggestions et des commentaires sur la nouvelle installation partag\u00e9e.Au nom de l\u2019\u00e9quipe de projet, NVision Insight Group, cabinet d\u2019expertise-conseil autochtone \u00e0 Ottawa effectue un sondage en ligne sur la consultation des Autochtones.","breadcrumb":{"@id":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/#primaryimage","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-C_Albert-East-scaled.jpg","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/VCAM-C_Albert-East-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/adisoke.ca\/fr\/news-post\/sondage-en-ligne-aupres-des-autochtones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/adisoke.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Sondage en ligne aupr\u00e8s des Autochtones"}]},{"@type":"WebSite","@id":"https:\/\/adisoke.ca\/#website","url":"https:\/\/adisoke.ca\/","name":"\u0101dis\u014dke","description":"Stories live here.","publisher":{"@id":"https:\/\/adisoke.ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/adisoke.ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/adisoke.ca\/#organization","name":"\u0101dis\u014dke","url":"https:\/\/adisoke.ca\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/","url":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","contentUrl":"https:\/\/adisoke.ca\/wp-content\/uploads\/2023\/09\/a\u0304diso\u0304ke_23_Wordmark_B_RGB.png","width":850,"height":202,"caption":"\u0101dis\u014dke"},"image":{"@id":"https:\/\/adisoke.ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2572","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post"}],"about":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/types\/news-post"}],"author":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2572\/revisions"}],"predecessor-version":[{"id":5262,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-post\/2572\/revisions\/5262"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media\/2578"}],"wp:attachment":[{"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/media?parent=2572"}],"wp:term":[{"taxonomy":"news-category","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-category?post=2572"},{"taxonomy":"news-year","embeddable":true,"href":"https:\/\/adisoke.ca\/fr\/wp-json\/wp\/v2\/news-year?post=2572"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}